{"id":13,"date":"2018-03-22T21:06:46","date_gmt":"2018-03-22T21:06:46","guid":{"rendered":"https:\/\/liviucerchez.com\/papaia\/?page_id=13"},"modified":"2018-09-08T20:37:36","modified_gmt":"2018-09-08T18:37:36","slug":"contact","status":"publish","type":"page","link":"https:\/\/liviucerchez.com\/papaia\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"<p>Our door is always open to new projects and collaborations. Hire us or just say hello. We&#8217;d love to hear from you!<\/p>\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f35-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"35\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/papaia\/wp-json\/wp\/v2\/pages\/13#wpcf7-f35-o1\" method=\"post\" class=\"wpcf7-form init demo\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"35\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f35-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p><label for=\"your_name\" class=\"sr-only\">Name<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your_name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" id=\"your_name\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Your name...\" value=\"\" type=\"text\" name=\"your_name\" \/><\/span><label for=\"your_email\" class=\"sr-only\">Email<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your_email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" id=\"your_email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Your email...\" value=\"\" type=\"email\" name=\"your_email\" \/><\/span><label for=\"your_message\" class=\"sr-only\">Message<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your_message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" id=\"your_message\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Here goes the message...\" name=\"your_message\"><\/textarea><\/span><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Send Message\" \/>\n<\/p><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"79\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Our door is always open to new projects and collaborations. Hire us or just say hello. We&#8217;d love to hear from you!<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-featured-images.php","meta":{"footnotes":""},"class_list":["post-13","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/liviucerchez.com\/papaia\/wp-json\/wp\/v2\/pages\/13","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/liviucerchez.com\/papaia\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/liviucerchez.com\/papaia\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/liviucerchez.com\/papaia\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/liviucerchez.com\/papaia\/wp-json\/wp\/v2\/comments?post=13"}],"version-history":[{"count":0,"href":"https:\/\/liviucerchez.com\/papaia\/wp-json\/wp\/v2\/pages\/13\/revisions"}],"wp:attachment":[{"href":"https:\/\/liviucerchez.com\/papaia\/wp-json\/wp\/v2\/media?parent=13"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}